		{"id":1605,"date":"2021-01-12T08:00:36","date_gmt":"2021-01-12T14:00:36","guid":{"rendered":"https:\/\/idesaa.edu.mx\/blog\/?p=1605"},"modified":"2025-06-04T18:51:15","modified_gmt":"2025-06-05T00:51:15","slug":"conocerse-a-si-mismo-avanza-en-tu-carrera-y-aporta-mas-valor-a-tu-empresa","status":"publish","type":"post","link":"https:\/\/idesaa.edu.mx\/blog\/conocerse-a-si-mismo-avanza-en-tu-carrera-y-aporta-mas-valor-a-tu-empresa\/","title":{"rendered":"Conocerse a s\u00ed mismo: avanza en tu carrera y aporta m\u00e1s valor a tu empresa"},"content":{"rendered":"<p><strong>Hace tiempo le\u00ed una edici\u00f3n especial sobre Liderazgo publicada por Harvard Business Review en la que se realzaba la importancia de conocerse a s\u00ed mismo. Rescat\u00e9 dos ideas principales:<\/strong><\/p>\n<ul>\n<li>Ninguna herramienta puede ayudar al l\u00edder que le falta autoconocimiento.<\/li>\n<li>Los l\u00edderes deben ayudar a su gente a descubrir para qu\u00e9 son buenos, deben fomentar el <a class=\"enlaces-articulo\" href=\"https:\/\/idesaa.edu.mx\/blog\/conocerse-a-si-mismo-avanza-en-tu-carrera-y-aporta-mas-valor-a-tu-empresa\/\" target=\"_blank\" rel=\"noopener\">autoconocimiento<\/a>.<\/li>\n<\/ul>\n<p>Me llam\u00f3 la atenci\u00f3n que, siendo una edici\u00f3n que abordaba exclusivamente el tema de liderazgo, se le diera tanto \u00e9nfasis a la importancia de <a class=\"enlaces-articulo\" href=\"https:\/\/idesaa.edu.mx\/blog\/no-es-el-compas-el-que-traza-el-circulo-sino-el-dibujante-conocerse-a-uno-mismo\/\" target=\"_blank\" rel=\"noopener\">conocerse a s\u00ed mismo<\/a>. La verdad es que cada vez lo entiendo m\u00e1s.<\/p>\n<blockquote><p>Conocerte a ti mismo te ayudar\u00e1 a entender lo que tienes que hacer para crecer y subir tu capacidad profesional.<\/p><\/blockquote>\n<p>En el contexto del desarrollo, conocerse a s\u00ed mismo es parte de la <a class=\"enlaces-articulo\" href=\"https:\/\/idesaa.edu.mx\/blog\/como-impacta-la-inteligencia-emocional-en-tu-satisfaccion-personal-y-en-tu-productividad\/\" target=\"_blank\" rel=\"noopener\">inteligencia emocional<\/a> y esta a su vez, es parte de la capacidad que tiene una persona en el \u00e1mbito profesional. &nbsp;Por tanto, si la persona practica el autoconocimiento, aumenta su inteligencia emocional y en consecuencia sube su capacidad profesional.<\/p>\n<p><strong>Conocerse a s\u00ed mismo es valioso -para iniciar- porque vivir en la verdad es mejor que vivir en la mentira o en el error.<\/strong> Esa creo que es raz\u00f3n suficiente. Sin embargo, hay otras ventajas como, por ejemplo, saber distinguir entre lo que es aparente y lo que es real. Si una persona con quien te relacionas considera que eres buen solucionador de problemas pues qu\u00e9 bien. Pero en \u00faltima instancia, es tu responsabilidad saber si ese juicio es acertado o no, y en consecuencia tomar las decisiones correctas para mejorar esa capacidad.<\/p>\n<p><strong>\u00bfQu\u00e9 puedes conocer de ti mismo?<\/strong> En el \u00e1mbito personal tus valores, prioridades, temperamento, si eres introvertido o extrovertido, si eres estructurado o soportas la ambig\u00fcedad, entre muchas otras cosas.<\/p>\n<h2 style=\"font-size: 20px;\">Y con respecto a tus capacidades en el \u00e1mbito profesional es importante que tengas claridad de qu\u00e9 tanto valor aportas a tu empresa. Una escala para evaluar tus capacidades es la siguiente:<\/h2>\n<ol>\n<li>No alcanzas a comprender qu\u00e9 debes hacer, o bien no sabes hacer lo que te piden.<\/li>\n<li>Lo que te piden hacer lo haces de dudosa calidad, y lo justificas diciendo que son \u201cerrores normales\u201d. O bien, aunque sabes hacerlo bien, necesitas que te est\u00e9n motivando o recordando.<\/li>\n<li>Lo que te piden hacer lo haces bien en forma consistente.<\/li>\n<li>Eres capaz de generar ideas de mejora para tu actividad laboral y las implementas usando hechos y datos.<\/li>\n<li>Eres capaz de darle mayor valor al puesto y a tu empresa; por ti mismo generas y llevas a cabo nuevos proyectos.<\/li>\n<\/ol>\n<p>Advierte que en los \u00faltimos dos escalones las oportunidades de mejora nacen de ti mismo. <a class=\"enlaces-articulo\" href=\"https:\/\/idesaa.edu.mx\/blog\/cual-es-tu-nivel-de-energia\/\" target=\"_blank\" rel=\"noopener\">\u00bfEn qu\u00e9 nivel est\u00e1s?<\/a> He visto muchos casos de personas que se sobrevaloran. Otros, por el contrario, no se dan cuenta de lo que valen para su empresa.<\/p>\n<p>Para conocerte mejor y ponderar tu nivel profesional ayuda explorar o \u201cconocer el mundo\u201d para tener puntos de referencia en tu reflexi\u00f3n. Investiga qu\u00e9 hacen otras personas que se dedican a lo mismo que t\u00fa, visita empresas, dialoga con personas que no forman parte de tu c\u00edrculo normal de relaciones, lee libros y revistas, asiste a congresos, capac\u00edtate. Un buen diagn\u00f3stico integrado por cuestionarios, pruebas, y entrevistas con especialistas seguramente tambi\u00e9n te ser\u00e1n de mucha utilidad.<\/p>\n<p><strong>Recapitulando, conocerse a s\u00ed mismo te ayudar\u00e1 a entender lo que tienes que hacer para crecer y subir tu capacidad profesional. Con ello estar\u00e1s en posibilidad de aportar mayor valor para tu empresa.<\/strong><\/p>\n<hr class=\"separador\">\n<p><em>El cambio organizacional es una necesidad empresarial para crecer y tener \u00e9xito, sobre todo en escenarios vol\u00e1tiles, complejos y de incertidumbre. En IDESAA tenemos amplia experiencia en desarrollar las capacidades necesarias en los l\u00edderes del cambio organizacional para que puedan gestionarlo correctamente e impulsarlo a trav\u00e9s de mejores estrategias.<\/em><\/p>\n<p><em>Contacta a un asesor IDESAA para m\u00e1s informaci\u00f3n de soluciones de capacitaci\u00f3n. <a id=\"enlace-cierres\" href=\"https:\/\/idesaa.edu.mx\/contactanos.php\" target=\"_blank\" rel=\"noopener\">Contacto<\/a><\/em><\/p>\n<style>#promo-cursos{background:url(https:\/\/idesaa.edu.mx\/bannersblog\/blog-banner-curso-competencias-gerenciales.webp);background-repeat:no-repeat;background-size:cover;background-position:center}@media screen and (max-width: 768px){#promo-cursos{background:url(https:\/\/idesaa.edu.mx\/bannersblog\/blog-banner-curso-competencias-gerenciales-movil.webp);background-repeat:no-repeat;background-size:cover;background-position:top}<\/style>\n<div id=\"promo-cursos\">\n<div>\n<p>Conoce nuestro<br \/>\nDiplomado en Desarrollo de Competencias Gerenciales<\/p>\n<p><a href=\"https:\/\/idesaa.edu.mx\/diplomado-desarrollo-competencias-gerenciales?utm_source=BLOG&amp;utm_medium=BLOG&amp;utm_campaign=BLOG_IDESAA&amp;utm_id=BLOG_IDESAA\n\">Me interesa<\/a><\/p>\n<\/div>\n<\/div>\n<hr>\n<p><strong><span style=\"color: #333399;\">Conoce al autor:<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #333399;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7231\" src=\"https:\/\/idesaa.edu.mx\/blog\/wp-content\/uploads\/2025\/01\/img-autor-rene-m.webp\" alt=\"\" width=\"140\" height=\"145\" srcset=\"https:\/\/idesaa.edu.mx\/blog\/wp-content\/uploads\/2025\/01\/img-autor-rene-m.webp 900w, https:\/\/idesaa.edu.mx\/blog\/wp-content\/uploads\/2025\/01\/img-autor-rene-m-289x300.webp 289w, https:\/\/idesaa.edu.mx\/blog\/wp-content\/uploads\/2025\/01\/img-autor-rene-m-768x798.webp 768w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/>Ren\u00e9 Mena Seifert<\/span><\/strong>&nbsp;es creador, fundador y CEO de IDESAA, TRUE e-Learning y del Foro Pro-Talento Empresarial. Su especialidad es el dise\u00f1o e implementaci\u00f3n de soluciones de negocio basadas en proyectos de capacitaci\u00f3n y desarrollo de talento hechos a la medida de las empresas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace tiempo le\u00ed una edici\u00f3n especial sobre Liderazgo publicada por Harvard Business Review en la que se realzaba la importancia de conocerse a s\u00ed mismo. Rescat\u00e9 dos ideas principales: Ninguna herramienta puede ayudar al l\u00edder que le falta autoconocimiento. Los l\u00edderes deben ayudar a su gente a descubrir para qu\u00e9 son buenos, deben fomentar el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[703],"tags":[401,72,569],"class_list":["post-1605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-desarrollo-profesional","tag-autoconocimiento","tag-desarrollo-de-talento","tag-desarrollo-personal"],"_links":{"self":[{"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/posts\/1605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/comments?post=1605"}],"version-history":[{"count":0,"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/posts\/1605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/media\/1611"}],"wp:attachment":[{"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/media?parent=1605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/categories?post=1605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idesaa.edu.mx\/blog\/wp-json\/wp\/v2\/tags?post=1605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}